{"id":2201,"date":"2026-04-12T13:49:09","date_gmt":"2026-04-12T11:49:09","guid":{"rendered":"https:\/\/masala-movement.de\/?post_type=event&#038;p=2201"},"modified":"2026-06-19T07:48:05","modified_gmt":"2026-06-19T05:48:05","slug":"mm-records-refuge-worldwide-3","status":"publish","type":"event","link":"https:\/\/masala-movement.de\/en\/event\/mm-records-refuge-worldwide-3\/","title":{"rendered":"MM Records @ Refuge Worldwide"},"content":{"rendered":"<section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p data-start=\"232\" data-end=\"611\">In der dritten Ausgabe unserer Radioserie bei Refuge Worldwide\u00a0teilt der Musikproduzent und Labelmanager von Masala Movement, Todh Teri, eine pers\u00f6nliche Auswahl von Tracks, die seine Arbeit und sein Leben gepr\u00e4gt und inspiriert haben \u2013 von indischer Klassik bis hin zu modernen elektronischen Kl\u00e4ngen<\/p>\n<p data-start=\"613\" data-end=\"797\">Mit dem Masala Movement Label schaffen wir eine Plattform f\u00fcr K\u00fcnstler*innen aus der s\u00fcdasiatischen und postmigrantischen Diaspora, die Clubkultur, Identit\u00e4t und Klang neu verbinden.<\/p>\n<p data-start=\"799\" data-end=\"1024\">Die Sendung l\u00e4uft auf Refuge Worldwide \u2013 einer unabh\u00e4ngigen Radiostation und Community-Plattform in Berlin-Neuk\u00f6lln, die seit 2015 R\u00e4ume f\u00fcr vielf\u00e4ltige Stimmen, musikalische Entdeckungen und sozialen Austausch schafft.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"In der dritten Ausgabe unserer Radioserie bei Refuge Worldwide\u00a0teilt der Musikproduzent und Labelmanager von Masala Movement, Todh Teri, eine pers\u00f6nliche Auswahl von Tracks, die seine Arbeit und sein Leben gepr\u00e4gt und inspiriert haben \u2013 von indischer Klassik bis hin zu modernen elektronischen Kl\u00e4ngen Mit dem Masala Movement Label schaffen wir eine Plattform f\u00fcr K\u00fcnstler*innen aus...","protected":false},"featured_media":1680,"template":"","meta":{"_acf_changed":false,"footnotes":""},"mm_event_category":[42],"mm_event_tags":[12],"class_list":["post-2201","event","type-event","status-publish","has-post-thumbnail","hentry","mm_event_category-music","mm_event_tags-past"],"acf":[],"_links":{"self":[{"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/event\/2201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":1,"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/event\/2201\/revisions"}],"predecessor-version":[{"id":2203,"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/event\/2201\/revisions\/2203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/media\/1680"}],"wp:attachment":[{"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/media?parent=2201"}],"wp:term":[{"taxonomy":"mm_event_category","embeddable":true,"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/mm_event_category?post=2201"},{"taxonomy":"mm_event_tags","embeddable":true,"href":"https:\/\/masala-movement.de\/en\/wp-json\/wp\/v2\/mm_event_tags?post=2201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}